{"id":50394,"date":"2021-10-20T08:32:29","date_gmt":"2021-10-20T06:32:29","guid":{"rendered":"https:\/\/www.levriers-du-sud.org\/site\/?p=50394"},"modified":"2021-11-17T17:49:43","modified_gmt":"2021-11-17T16:49:43","slug":"luna-2","status":"publish","type":"post","link":"https:\/\/www.levriers-du-sud.org\/site\/20\/10\/2021\/luna-2\/","title":{"rendered":"Luna&#8230;adoptee a madrid"},"content":{"rendered":"<p><strong>Type :<\/strong>\u00a0 x galgo<br \/>\n<strong>Sexe : <\/strong>femelle<br \/>\n<strong>Age : <\/strong>06\/2020<br \/>\n<strong>Sant\u00e9 <\/strong>:st\u00e9rilis\u00e9e, n\u00e9gative aux 3Mm<strong><br \/>\nSituation: <\/strong>en refuge ( ACUNR)\u00a0\u00a0<strong><br \/>\n<\/strong><\/p>\n<p><strong>Commentaire:<br \/>\n<\/strong>Luna a \u00e9t\u00e9 c\u00e9d\u00e9e par son ancien propri\u00e9taire. Luna est un concentr\u00e9 de gait\u00e9 et de vivalit\u00e9. Elle a toujours v\u00e9cu dans une ferme en chenil et ne connait rien de la vie, des promenades&#8230; MAis elle est pleine d &lsquo;envie de connaitre de nouvelles choses et elle s&rsquo;habituera rapidement \u00e0 une vraie vie. Elle recherche les caresses et l &lsquo;attention des b\u00e9n\u00e9voles. Elle a de bonnes relations avec tous les autres chiens.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50398\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna4-300x285.jpg\" alt=\"\" width=\"281\" height=\"268\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna4-300x285.jpg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna4-768x729.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna4.jpg 945w\" sizes=\"auto, (max-width: 281px) 100vw, 281px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50401\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna-225x300.jpg\" alt=\"\" width=\"199\" height=\"266\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna-225x300.jpg 225w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna-768x1024.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna-1152x1536.jpg 1152w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna.jpg 1333w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-50399\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna6-250x300.jpg\" alt=\"\" width=\"250\" height=\"300\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna6-250x300.jpg 250w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna6-853x1024.jpg 853w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna6-768x922.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna6.jpg 945w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-50400\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna2-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna2-225x300.jpg 225w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna2-768x1024.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna2-1152x1536.jpg 1152w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna2.jpg 1481w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50395\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna-m-200x300.jpg\" alt=\"\" width=\"211\" height=\"317\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna-m-200x300.jpg 200w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna-m-683x1024.jpg 683w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna-m-768x1152.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna-m-1024x1536.jpg 1024w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna-m.jpg 1176w\" sizes=\"auto, (max-width: 211px) 100vw, 211px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50397\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna5-225x300.jpg\" alt=\"\" width=\"242\" height=\"323\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna5-225x300.jpg 225w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna5-768x1024.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna5-1152x1536.jpg 1152w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/luna5.jpg 1176w\" sizes=\"auto, (max-width: 242px) 100vw, 242px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Type :\u00a0 x galgo Sexe : femelle Age : 06\/2020 Sant\u00e9 :st\u00e9rilis\u00e9e, n\u00e9gative aux 3Mm Situation: en refuge ( ACUNR)\u00a0\u00a0 Commentaire: Luna a \u00e9t\u00e9 c\u00e9d\u00e9e par son ancien propri\u00e9taire. Luna est un concentr\u00e9 de gait\u00e9 et de vivalit\u00e9. Elle a toujours v\u00e9cu dans une ferme en chenil et ne connait rien de la vie, des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,13],"tags":[],"class_list":["post-50394","post","type-post","status-publish","format-standard","hentry","category-galgos-adoptes","category-ok-chiens"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts\/50394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/comments?post=50394"}],"version-history":[{"count":2,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts\/50394\/revisions"}],"predecessor-version":[{"id":50734,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts\/50394\/revisions\/50734"}],"wp:attachment":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/media?parent=50394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/categories?post=50394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/tags?post=50394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}