{"id":50532,"date":"2021-10-31T13:02:50","date_gmt":"2021-10-31T11:02:50","guid":{"rendered":"https:\/\/www.levriers-du-sud.org\/site\/?p=50532"},"modified":"2021-11-06T11:38:09","modified_gmt":"2021-11-06T10:38:09","slug":"bella-5","status":"publish","type":"post","link":"https:\/\/www.levriers-du-sud.org\/site\/31\/10\/2021\/bella-5\/","title":{"rendered":"Bella&#8230;adopt\u00e9e chez Acunr"},"content":{"rendered":"<p><strong>Type :<\/strong>podenco<br \/>\n<strong>Sexe :<\/strong> femelle<br \/>\n<strong>Age : <\/strong>03\/2018<br \/>\n<strong>Sant\u00e9 <\/strong>:st\u00e9rilis\u00e9e<strong>,<\/strong>\u00a0negative aux 3MM<strong><br \/>\nSituation: <\/strong>en refuge ( ACUNR)<strong><br \/>\n<\/strong><\/p>\n<p><strong>Commentaire :<br \/>\n<\/strong>Bella avait \u00e9t\u00e9 prise en charge par nos amis de Acunr avec plusieurs autres podencas. Les personnes qui les avaient, suite \u00e0 de grosses difficult\u00e9s personnelles, ne pouvaient pas les garder. Bella est une podenca bien dans ses pattes, qui a d\u00e9j\u00e0 v\u00e9cu en maison et qui n a aucun souci avec les gens ou les autres chiens. Elle est tr\u00e8s douce et caline.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50533\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/brlla-c-300x200.jpg\" alt=\"\" width=\"279\" height=\"186\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/brlla-c-300x200.jpg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/brlla-c-1024x683.jpg 1024w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/brlla-c-768x512.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/brlla-c-1536x1024.jpg 1536w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/brlla-c.jpg 1764w\" sizes=\"auto, (max-width: 279px) 100vw, 279px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50534\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-d-300x200.jpg\" alt=\"\" width=\"279\" height=\"186\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-d-300x200.jpg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-d-1024x683.jpg 1024w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-d-768x512.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-d-1536x1024.jpg 1536w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-d.jpg 1764w\" sizes=\"auto, (max-width: 279px) 100vw, 279px\" \/><!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-50535\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-v-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-v-200x300.jpg 200w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-v-683x1024.jpg 683w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-v-768x1152.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-v-1024x1536.jpg 1024w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-v.jpg 1176w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-50536\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-6-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-6-300x200.jpg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-6-1024x683.jpg 1024w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-6-768x512.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-6-1536x1024.jpg 1536w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-6.jpg 1764w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-50537\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-f-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-f-200x300.jpg 200w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-f-683x1024.jpg 683w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-f-768x1152.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-f-1024x1536.jpg 1024w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-f.jpg 1176w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-50538\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-200x300.jpg 200w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-683x1024.jpg 683w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-768x1152.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella-1024x1536.jpg 1024w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/10\/bella.jpg 1176w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Type :podenco Sexe : femelle Age : 03\/2018 Sant\u00e9 :st\u00e9rilis\u00e9e,\u00a0negative aux 3MM Situation: en refuge ( ACUNR) Commentaire : Bella avait \u00e9t\u00e9 prise en charge par nos amis de Acunr avec plusieurs autres podencas. Les personnes qui les avaient, suite \u00e0 de grosses difficult\u00e9s personnelles, ne pouvaient pas les garder. Bella est une podenca bien [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,20],"tags":[],"class_list":["post-50532","post","type-post","status-publish","format-standard","hentry","category-ok-chiens","category-podencos-adoptes"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts\/50532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/comments?post=50532"}],"version-history":[{"count":2,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts\/50532\/revisions"}],"predecessor-version":[{"id":50683,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts\/50532\/revisions\/50683"}],"wp:attachment":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/media?parent=50532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/categories?post=50532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/tags?post=50532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}