{"id":50685,"date":"2022-05-09T13:00:40","date_gmt":"2022-05-09T11:00:40","guid":{"rendered":"https:\/\/www.levriers-du-sud.org\/site\/?p=50685"},"modified":"2022-09-02T15:27:34","modified_gmt":"2022-09-02T13:27:34","slug":"syria","status":"publish","type":"post","link":"https:\/\/www.levriers-du-sud.org\/site\/09\/05\/2022\/syria\/","title":{"rendered":"Syria&#8230;adoptee"},"content":{"rendered":"<p><strong>Type :<\/strong> podenco<br \/>\n<strong>Sexe :<\/strong> femelle<br \/>\n<strong>Age : <\/strong>10\/2020<br \/>\n<strong>Sant\u00e9 :<\/strong> sterillisee\u00a0 negative aux 3MM,43cm, 13.800kgs<br \/>\n<strong>Situation: <\/strong>en pension \u00e0 notre charge<strong><br \/>\n<\/strong><\/p>\n<p><strong>Commentaire :<br \/>\n<\/strong>Nous avons r\u00e9pondu \u00e0 un SOS pour cette podenca abandonn\u00e9e, apparemment elle avait du avoir des chiots mais ils n&rsquo;\u00e9taient plus l\u00e0&#8230; Nous l&rsquo;avons mise en s\u00e9curit\u00e9 en pension et elle reprend des forces. C&rsquo;est une chienne adorable et joueuse ; elle n&rsquo;a pas peur de l humain, elle est juste timide au d\u00e9but, et elle s&rsquo;entend avec tous les chiens. C&rsquo;est une petite chienne \u00e9nergique et pleine de vie.<\/p>\n<p><strong>Parrain\u00e9e par Magali M 60.00 eur mensuel<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-51444\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0047-236x300.jpg\" alt=\"\" width=\"221\" height=\"281\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0047-236x300.jpg 236w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0047-806x1024.jpg 806w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0047-768x975.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0047-1210x1536.jpg 1210w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0047.jpg 1260w\" sizes=\"auto, (max-width: 221px) 100vw, 221px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-51445\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0048-178x300.jpg\" alt=\"\" width=\"166\" height=\"280\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0048-178x300.jpg 178w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0048-608x1024.jpg 608w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0048-768x1293.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0048-912x1536.jpg 912w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0048.jpg 950w\" sizes=\"auto, (max-width: 166px) 100vw, 166px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-51446\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0049-185x300.jpg\" alt=\"\" width=\"170\" height=\"276\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0049-185x300.jpg 185w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0049-632x1024.jpg 632w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0049-768x1245.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0049.jpg 870w\" sizes=\"auto, (max-width: 170px) 100vw, 170px\" \/><!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-51447\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0050-245x300.jpg\" alt=\"\" width=\"245\" height=\"300\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0050-245x300.jpg 245w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0050-835x1024.jpg 835w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0050-768x942.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0050.jpg 908w\" sizes=\"auto, (max-width: 245px) 100vw, 245px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-51449\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0053-221x300.jpg\" alt=\"\" width=\"221\" height=\"300\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0053-221x300.jpg 221w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0053-754x1024.jpg 754w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0053-768x1043.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0053-1131x1536.jpg 1131w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0053.jpg 1178w\" sizes=\"auto, (max-width: 221px) 100vw, 221px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-51448\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0051-300x246.jpg\" alt=\"\" width=\"300\" height=\"246\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0051-300x246.jpg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0051-1024x839.jpg 1024w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0051-768x629.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0051-1536x1259.jpg 1536w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0051.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-51452\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0056-278x300.jpg\" alt=\"\" width=\"229\" height=\"247\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0056-278x300.jpg 278w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0056-950x1024.jpg 950w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0056-768x828.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0056.jpg 1316w\" sizes=\"auto, (max-width: 229px) 100vw, 229px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-51451\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0055-192x300.jpg\" alt=\"\" width=\"185\" height=\"289\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0055-192x300.jpg 192w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0055-656x1024.jpg 656w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0055-768x1199.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0055.jpg 959w\" sizes=\"auto, (max-width: 185px) 100vw, 185px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-51453\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0057-165x300.jpg\" alt=\"\" width=\"159\" height=\"289\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0057-165x300.jpg 165w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0057-562x1024.jpg 562w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0057-768x1398.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0057.jpg 798w\" sizes=\"auto, (max-width: 159px) 100vw, 159px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-51450\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0054-160x300.jpg\" alt=\"\" width=\"155\" height=\"290\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0054-160x300.jpg 160w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0054-547x1024.jpg 547w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0054-768x1437.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0054-821x1536.jpg 821w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/IMG-20220224-WA0054.jpg 855w\" sizes=\"auto, (max-width: 155px) 100vw, 155px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50689\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/253783248_1770036006521921_4982325505757877683_n-300x300.jpg\" alt=\"\" width=\"280\" height=\"280\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/253783248_1770036006521921_4982325505757877683_n-300x300.jpg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/253783248_1770036006521921_4982325505757877683_n-150x150.jpg 150w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/253783248_1770036006521921_4982325505757877683_n-768x768.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/253783248_1770036006521921_4982325505757877683_n.jpg 800w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50690\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/254292403_309803737638897_8760370669220185517_n-300x300.jpg\" alt=\"\" width=\"279\" height=\"279\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/254292403_309803737638897_8760370669220185517_n-300x300.jpg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/254292403_309803737638897_8760370669220185517_n-150x150.jpg 150w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/254292403_309803737638897_8760370669220185517_n-768x768.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/254292403_309803737638897_8760370669220185517_n.jpg 800w\" sizes=\"auto, (max-width: 279px) 100vw, 279px\" \/><!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50686\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/syria6-169x300.jpg\" alt=\"\" width=\"168\" height=\"298\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/syria6-169x300.jpg 169w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/syria6.jpg 422w\" sizes=\"auto, (max-width: 168px) 100vw, 168px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-50687\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/syria8-169x300.jpg\" alt=\"\" width=\"169\" height=\"300\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/syria8-169x300.jpg 169w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/syria8.jpg 422w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-50688\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/syria9-169x300.jpg\" alt=\"\" width=\"169\" height=\"300\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/syria9-169x300.jpg 169w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2021\/11\/syria9.jpg 422w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Type : podenco Sexe : femelle Age : 10\/2020 Sant\u00e9 : sterillisee\u00a0 negative aux 3MM,43cm, 13.800kgs Situation: en pension \u00e0 notre charge Commentaire : Nous avons r\u00e9pondu \u00e0 un SOS pour cette podenca abandonn\u00e9e, apparemment elle avait du avoir des chiots mais ils n&rsquo;\u00e9taient plus l\u00e0&#8230; Nous l&rsquo;avons mise en s\u00e9curit\u00e9 en pension et elle [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,13,20],"tags":[],"class_list":["post-50685","post","type-post","status-publish","format-standard","hentry","category-ok-chats","category-ok-chiens","category-podencos-adoptes"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts\/50685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/comments?post=50685"}],"version-history":[{"count":8,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts\/50685\/revisions"}],"predecessor-version":[{"id":52801,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts\/50685\/revisions\/52801"}],"wp:attachment":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/media?parent=50685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/categories?post=50685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/tags?post=50685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}