{"id":52113,"date":"2022-05-29T16:47:46","date_gmt":"2022-05-29T14:47:46","guid":{"rendered":"https:\/\/www.levriers-du-sud.org\/site\/?p=52113"},"modified":"2022-06-27T13:58:40","modified_gmt":"2022-06-27T11:58:40","slug":"merle","status":"publish","type":"post","link":"https:\/\/www.levriers-du-sud.org\/site\/29\/05\/2022\/merle\/","title":{"rendered":"Merle&#8230;adopte"},"content":{"rendered":"<p><strong>Type :<\/strong> galgo<br \/>\n<strong>Sexe :<\/strong> femelle<br \/>\n<strong>Age : <\/strong>06\/2018<br \/>\n<strong>Sant\u00e9 : <\/strong>\u00a0st\u00e9rilis\u00e9e,\u00a0 \u00a066 cm, 24\u00a0 kgs, negative\u00a0 maladies<br \/>\n<strong>Situation: <\/strong>en refuge (GDS)<strong><br \/>\n<\/strong><\/p>\n<p><strong>Commentaire :<br \/>\n<\/strong>Merle a \u00e9t\u00e9 sauv\u00e9e de la perrera de Cordoux. Elle est douce et<span class=\"Y2IQFc\" lang=\"fr\"> calme, un peu timide au d\u00e9but mais pas paniqu\u00e9e. C&rsquo;est une galguita qui, avec seulement quelques jours d&rsquo;adaptation, est tr\u00e8s affectueuse. Avec les autres chiens, elle est sociable et soumise, pas dominante. Elle est suiveuse, s&rsquo;il y a d&rsquo;autres chiens \u00e0 la maison elle se sentira plus \u00e0 l&rsquo;aise pour s&rsquo;adapter.\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-52114\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/merle7-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/merle7-225x300.jpeg 225w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/merle7.jpeg 640w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-52117\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/merle4-258x300.jpeg\" alt=\"\" width=\"258\" height=\"300\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/merle4-258x300.jpeg 258w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/merle4.jpeg 640w\" sizes=\"auto, (max-width: 258px) 100vw, 258px\" \/><!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-52115\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/merle6-300x225.jpeg\" alt=\"\" width=\"280\" height=\"210\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/merle6-300x225.jpeg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/merle6.jpeg 639w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-52116\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/merle5-300x225.jpeg\" alt=\"\" width=\"280\" height=\"210\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/merle5-300x225.jpeg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/merle5-768x575.jpeg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/merle5.jpeg 943w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-52118\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/merle3-300x225.jpeg\" alt=\"\" width=\"279\" height=\"209\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/merle3-300x225.jpeg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/merle3-768x576.jpeg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/merle3.jpeg 996w\" sizes=\"auto, (max-width: 279px) 100vw, 279px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-52120\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/mere-300x225.jpeg\" alt=\"\" width=\"280\" height=\"210\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/mere-300x225.jpeg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/mere-768x577.jpeg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/mere.jpeg 1023w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Type : galgo Sexe : femelle Age : 06\/2018 Sant\u00e9 : \u00a0st\u00e9rilis\u00e9e,\u00a0 \u00a066 cm, 24\u00a0 kgs, negative\u00a0 maladies Situation: en refuge (GDS) Commentaire : Merle a \u00e9t\u00e9 sauv\u00e9e de la perrera de Cordoux. Elle est douce et calme, un peu timide au d\u00e9but mais pas paniqu\u00e9e. C&rsquo;est une galguita qui, avec seulement quelques jours d&rsquo;adaptation, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19,14,13],"tags":[],"class_list":["post-52113","post","type-post","status-publish","format-standard","hentry","category-galgos-adoptes","category-ok-chats","category-ok-chiens"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts\/52113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/comments?post=52113"}],"version-history":[{"count":2,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts\/52113\/revisions"}],"predecessor-version":[{"id":52311,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts\/52113\/revisions\/52311"}],"wp:attachment":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/media?parent=52113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/categories?post=52113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/tags?post=52113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}