{"id":52142,"date":"2022-05-29T17:14:22","date_gmt":"2022-05-29T15:14:22","guid":{"rendered":"https:\/\/www.levriers-du-sud.org\/site\/?p=52142"},"modified":"2022-10-05T15:44:12","modified_gmt":"2022-10-05T13:44:12","slug":"alheli","status":"publish","type":"post","link":"https:\/\/www.levriers-du-sud.org\/site\/29\/05\/2022\/alheli\/","title":{"rendered":"Alheli&#8230;adopte eb allemagne"},"content":{"rendered":"<p><strong>Type :<\/strong> podenco<br \/>\n<strong>Sexe :<\/strong> male<br \/>\n<strong>Age : <\/strong>03\/2021<br \/>\n<strong>Sant\u00e9 :<\/strong>negatif\u00a0 maladies;castr\u00e9<br \/>\n<strong>Situation: <\/strong>en refuge (GDS)<strong><br \/>\n<\/strong><\/p>\n<p><strong>Commentaire :<br \/>\n<\/strong><span class=\"Y2IQFc\" lang=\"fr\">Au d\u00e9but il sera un peu plus timide mais il s&rsquo;est vite habitu\u00e9 au refuge et il nous cherche toujours en nous demandant des caresses tr\u00e8s content, il continue juste \u00e0 \u00eatre un peu timide quand il voit de nouvelles personnes au refuge, mais c&rsquo;est normal consid\u00e9rant qu&rsquo;il grandit l\u00e0-bas et qu&rsquo;il n&rsquo;est pas habitu\u00e9 \u00e0 plus de monde que ses soignants. Il est amusant et dr\u00f4le, si les autres veulent jouer avec lui, il passe un bon moment, et s&rsquo;il est avec des chiens calmes, il s&rsquo;y habitue aussi, il est sociable et soumis, pas dominant. Il adore suivre les papillons et s&rsquo;allonger pour se reposer au soleil, c&rsquo;est un chien qui s&rsquo;il est adopt\u00e9 dans une maison avec un jardin bien cl\u00f4tur\u00e9, il passera un bon moment, surtout s&rsquo;il y a d&rsquo;autres chiens ou enfants.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-52143\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/ALHELI8-300x225.jpeg\" alt=\"\" width=\"280\" height=\"210\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/ALHELI8-300x225.jpeg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/ALHELI8-768x577.jpeg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/ALHELI8.jpeg 1023w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-52144\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/ALHELI6-300x225.jpeg\" alt=\"\" width=\"275\" height=\"206\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/ALHELI6-300x225.jpeg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/ALHELI6-768x576.jpeg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/ALHELI6.jpeg 851w\" sizes=\"auto, (max-width: 275px) 100vw, 275px\" \/>*<\/span><!--more--><\/p>\n<p><span class=\"Y2IQFc\" lang=\"fr\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-52145\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/LEHLI3-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/LEHLI3-225x300.jpeg 225w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/LEHLI3-768x1024.jpeg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/LEHLI3.jpeg 1024w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-52146\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/ALEHLI6-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/ALEHLI6-225x300.jpeg 225w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/ALEHLI6-768x1024.jpeg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/ALEHLI6.jpeg 1024w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/span><\/p>\n<p><span class=\"Y2IQFc\" lang=\"fr\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-52147\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/ALHELI-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/ALHELI-300x225.jpeg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/ALHELI-768x577.jpeg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/05\/ALHELI.jpeg 1023w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/>\n<\/span><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Type : podenco Sexe : male Age : 03\/2021 Sant\u00e9 :negatif\u00a0 maladies;castr\u00e9 Situation: en refuge (GDS) Commentaire : Au d\u00e9but il sera un peu plus timide mais il s&rsquo;est vite habitu\u00e9 au refuge et il nous cherche toujours en nous demandant des caresses tr\u00e8s content, il continue juste \u00e0 \u00eatre un peu timide quand il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,13,20],"tags":[],"class_list":["post-52142","post","type-post","status-publish","format-standard","hentry","category-ok-chats","category-ok-chiens","category-podencos-adoptes"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts\/52142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/comments?post=52142"}],"version-history":[{"count":2,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts\/52142\/revisions"}],"predecessor-version":[{"id":53045,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts\/52142\/revisions\/53045"}],"wp:attachment":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/media?parent=52142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/categories?post=52142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/tags?post=52142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}