{"id":53203,"date":"2022-11-07T18:57:12","date_gmt":"2022-11-07T16:57:12","guid":{"rendered":"https:\/\/www.levriers-du-sud.org\/site\/?p=53203"},"modified":"2023-07-14T17:23:03","modified_gmt":"2023-07-14T15:23:03","slug":"fiona-3","status":"publish","type":"post","link":"https:\/\/www.levriers-du-sud.org\/site\/07\/11\/2022\/fiona-3\/","title":{"rendered":"Fiona..adopt\u00e9e via une autre asso"},"content":{"rendered":"<p><strong>Type :<\/strong> croisee<br \/>\n<strong>Sexe :<\/strong> femelle<br \/>\n<strong>Age : <\/strong>12\/2021<br \/>\n<strong>Sant\u00e9 : <\/strong>st\u00e9rilis\u00e9e,\u00a0 n\u00e9gative aux 3MM,13 kgs<strong><br \/>\nSituation: <\/strong>en refuge (GEF)<strong><br \/>\n<\/strong><\/p>\n<p><strong>Commentaire :<br \/>\n<\/strong><span class=\"Y2IQFc\" lang=\"fr\">Fiona est venue avec une autre chienne de la fourri\u00e8re \u00e0 Malaga, o\u00f9 elles ont \u00e9t\u00e9 abandonn\u00e9es par leur \u00ab propri\u00e9taire \u00bb. Fiona est timide avec les gens et ne vous laisse pas l&rsquo;approcher, mais quand vous \u00eates pr\u00e8s d&rsquo;elle et que vous la caressez, elle vous laisse la caresser et\u2026 elle aime \u00e7a ! Nous savons que lorsqu&rsquo;ils arrivent avec une sorte de peur, c&rsquo;est un long processus et beaucoup de travail, mais Fiona va tr\u00e8s bien et en peu de temps elle s&rsquo;est beaucoup am\u00e9lior\u00e9e, c&rsquo;est juste une question de travailler un peu avec elle peu et lui montrant le bon c\u00f4t\u00e9 d&rsquo;\u00eatre humain. Elle s&rsquo;entend \u00e0 merveille avec les autres chiens du refuge. Fiona a besoin de patience, de beaucoup d&rsquo;amour et d&rsquo;un peu de confiance en elle pour \u00eatre compl\u00e8tement heureuse<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-53204\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA17-300x200.jpg\" alt=\"\" width=\"279\" height=\"186\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA17-300x200.jpg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA17-1024x682.jpg 1024w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA17-768x512.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA17.jpg 1205w\" sizes=\"auto, (max-width: 279px) 100vw, 279px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-53208\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA1-300x200.jpg\" alt=\"\" width=\"276\" height=\"184\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA1-300x200.jpg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA1-1024x682.jpg 1024w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA1-768x512.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA1.jpg 1205w\" sizes=\"auto, (max-width: 276px) 100vw, 276px\" \/><!--more--><\/p>\n<p><span class=\"Y2IQFc\" lang=\"fr\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-53205\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-MATILDA8-y-fiona-1-300x200.jpg\" alt=\"\" width=\"279\" height=\"186\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-MATILDA8-y-fiona-1-300x200.jpg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-MATILDA8-y-fiona-1-1024x682.jpg 1024w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-MATILDA8-y-fiona-1-768x512.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-MATILDA8-y-fiona-1.jpg 1205w\" sizes=\"auto, (max-width: 279px) 100vw, 279px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-53206\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA15-300x200.jpg\" alt=\"\" width=\"276\" height=\"184\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA15-300x200.jpg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA15-1024x682.jpg 1024w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA15-768x512.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA15.jpg 1205w\" sizes=\"auto, (max-width: 276px) 100vw, 276px\" \/> <\/span><\/p>\n<p><span class=\"Y2IQFc\" lang=\"fr\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-53207\" src=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA13-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA13-300x200.jpg 300w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA13-1024x682.jpg 1024w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA13-768x512.jpg 768w, https:\/\/www.levriers-du-sud.org\/site\/wp-content\/uploads\/2022\/11\/NC221022-FIONA13.jpg 1205w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/>\n<\/span><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Type : croisee Sexe : femelle Age : 12\/2021 Sant\u00e9 : st\u00e9rilis\u00e9e,\u00a0 n\u00e9gative aux 3MM,13 kgs Situation: en refuge (GEF) Commentaire : Fiona est venue avec une autre chienne de la fourri\u00e8re \u00e0 Malaga, o\u00f9 elles ont \u00e9t\u00e9 abandonn\u00e9es par leur \u00ab propri\u00e9taire \u00bb. Fiona est timide avec les gens et ne vous laisse pas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,13],"tags":[],"class_list":["post-53203","post","type-post","status-publish","format-standard","hentry","category-coup-de-pouce-adoptes","category-ok-chiens"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts\/53203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/comments?post=53203"}],"version-history":[{"count":4,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts\/53203\/revisions"}],"predecessor-version":[{"id":54722,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/posts\/53203\/revisions\/54722"}],"wp:attachment":[{"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/media?parent=53203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/categories?post=53203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.levriers-du-sud.org\/site\/wp-json\/wp\/v2\/tags?post=53203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}